{"id":22637,"date":"2026-07-15T14:53:13","date_gmt":"2026-07-15T12:53:13","guid":{"rendered":"https:\/\/www.ingridslaa.nl\/december-12-and-13-wendela-van-lynden\/"},"modified":"2026-07-15T14:58:11","modified_gmt":"2026-07-15T12:58:11","slug":"december-12-and-13-wendela-van-lynden","status":"publish","type":"post","link":"https:\/\/www.ingridslaa.nl\/en\/december-12-and-13-wendela-van-lynden\/","title":{"rendered":"December 12 and 13: Wendela van Lynden"},"content":{"rendered":"<div  class='flex_column av-nt43xi-f918e939004bc334b34f0e617590086b av_one_full  avia-builder-el-0  el_before_av_heading  avia-builder-el-first  first flex_column_div  '     ><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-mrm2mpu2-3159eb355a330161111d3a953edfe2a5\">\n#top .av-special-heading.av-mrm2mpu2-3159eb355a330161111d3a953edfe2a5{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-mrm2mpu2-3159eb355a330161111d3a953edfe2a5 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-mrm2mpu2-3159eb355a330161111d3a953edfe2a5 .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-mrm2mpu2-3159eb355a330161111d3a953edfe2a5 av-special-heading-h3  avia-builder-el-1  el_after_av_one_full  el_before_av_textblock '><h3 class='av-special-heading-tag '  itemprop=\"headline\"  >Dec. 12 and 13: Wendela van Lynden<\/h3><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div>\n<section  class='av_textblock_section av-mrm2xnk6-8346601c03369eea21f7562c62eacf3c '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class='avia_textblock'  itemprop=\"text\" ><p><strong>On December 12 and 13, Wendela van Lynden will be exhibiting three-dimensional objects at the gallery.<\/strong><\/p>\n<p>For Wendela van Lynden of Zeewolde, making art in this world is a process of creating and then dismantling. For her, art is an expression of a moment, a process you\u2019re immersed in. <\/p>\n<p>A work is born, lives for a moment, and is allowed to die. That process is both interesting and inspiring to Wendela. <\/p>\n<p>The materials she works with are usually worn and unattractive. They are fragile, discolored, and crumbling. <\/p>\n<p>Time wears it away.<\/p>\n<p>website: <a href=\"http:\/\/www.wendelavanlynden.nl\/\" target=\"_blank\" rel=\"noopener\">wendelavanlynden.nl<\/a><\/p>\n<\/div><\/section>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-mrm2p09e-b75dd61e2612b86f075a27130b2b78b6\">\n#top .avia-gallery.av-mrm2p09e-b75dd61e2612b86f075a27130b2b78b6 .avia-gallery-thumb a{\nwidth:16.6667%;\n}\n<\/style>\n<div  class='avia-gallery av-mrm2p09e-b75dd61e2612b86f075a27130b2b78b6 avia_animate_when_visible  avia-builder-el-3  el_after_av_textblock  avia-builder-el-last  avia_lazyload avia-gallery-animate avia-gallery-1'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><meta itemprop=\"contentURL\" content=\"https:\/\/www.ingridslaa.nl\/en\/december-12-and-13-wendela-van-lynden\/\"><div class='avia-gallery-thumb'><a href=\"https:\/\/www.ingridslaa.nl\/wp-content\/uploads\/2026\/07\/Wendela-2-690x1030.jpg\" data-srcset=\"https:\/\/www.ingridslaa.nl\/wp-content\/uploads\/2026\/07\/Wendela-2-690x1030.jpg 690w, https:\/\/www.ingridslaa.nl\/wp-content\/uploads\/2026\/07\/Wendela-2-201x300.jpg 201w, https:\/\/www.ingridslaa.nl\/wp-content\/uploads\/2026\/07\/Wendela-2-472x705.jpg 472w, https:\/\/www.ingridslaa.nl\/wp-content\/uploads\/2026\/07\/Wendela-2.jpg 725w\" data-sizes=\"(max-width: 690px) 100vw, 690px\" data-rel='gallery-1' data-prev-img='https:\/\/www.ingridslaa.nl\/wp-content\/uploads\/2026\/07\/Wendela-2-495x400.jpg' class='first_thumb lightbox ' data-onclick='1' title='Wendela 2'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-22639 avia-img-lazy-loading-not-22639\"   src=\"https:\/\/www.ingridslaa.nl\/wp-content\/uploads\/2026\/07\/Wendela-2.jpg\" width=\"725\" height=\"1083\"  title='Wendela 2' alt='' srcset=\"https:\/\/www.ingridslaa.nl\/wp-content\/uploads\/2026\/07\/Wendela-2.jpg 725w, https:\/\/www.ingridslaa.nl\/wp-content\/uploads\/2026\/07\/Wendela-2-201x300.jpg 201w, https:\/\/www.ingridslaa.nl\/wp-content\/uploads\/2026\/07\/Wendela-2-690x1030.jpg 690w, https:\/\/www.ingridslaa.nl\/wp-content\/uploads\/2026\/07\/Wendela-2-472x705.jpg 472w\" sizes=\"(max-width: 725px) 100vw, 725px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-22639 avia-img-lazy-loading-22639\"  width=\"495\" height=\"400\" src=\"https:\/\/www.ingridslaa.nl\/wp-content\/uploads\/2026\/07\/Wendela-2-495x400.jpg\" title='Wendela 2' alt='' \/><\/div><\/a><a href=\"https:\/\/www.ingridslaa.nl\/wp-content\/uploads\/2026\/07\/Wendela-3-714x1030.jpg\" data-srcset=\"https:\/\/www.ingridslaa.nl\/wp-content\/uploads\/2026\/07\/Wendela-3-714x1030.jpg 714w, https:\/\/www.ingridslaa.nl\/wp-content\/uploads\/2026\/07\/Wendela-3-208x300.jpg 208w, https:\/\/www.ingridslaa.nl\/wp-content\/uploads\/2026\/07\/Wendela-3-489x705.jpg 489w, https:\/\/www.ingridslaa.nl\/wp-content\/uploads\/2026\/07\/Wendela-3.jpg 725w\" data-sizes=\"(max-width: 714px) 100vw, 714px\" data-rel='gallery-1' data-prev-img='https:\/\/www.ingridslaa.nl\/wp-content\/uploads\/2026\/07\/Wendela-3-495x400.jpg' class='lightbox ' data-onclick='2' title='Wendela 3'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-22640 avia-img-lazy-loading-not-22640\"   src=\"https:\/\/www.ingridslaa.nl\/wp-content\/uploads\/2026\/07\/Wendela-3.jpg\" width=\"725\" height=\"1046\"  title='Wendela 3' alt='' srcset=\"https:\/\/www.ingridslaa.nl\/wp-content\/uploads\/2026\/07\/Wendela-3.jpg 725w, https:\/\/www.ingridslaa.nl\/wp-content\/uploads\/2026\/07\/Wendela-3-208x300.jpg 208w, https:\/\/www.ingridslaa.nl\/wp-content\/uploads\/2026\/07\/Wendela-3-714x1030.jpg 714w, https:\/\/www.ingridslaa.nl\/wp-content\/uploads\/2026\/07\/Wendela-3-489x705.jpg 489w\" sizes=\"(max-width: 725px) 100vw, 725px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-22640 avia-img-lazy-loading-22640\"  width=\"495\" height=\"400\" src=\"https:\/\/www.ingridslaa.nl\/wp-content\/uploads\/2026\/07\/Wendela-3-495x400.jpg\" title='Wendela 3' alt='' \/><\/div><\/a><a href=\"https:\/\/www.ingridslaa.nl\/wp-content\/uploads\/2026\/07\/Wendela-4-672x1030.jpg\" data-srcset=\"https:\/\/www.ingridslaa.nl\/wp-content\/uploads\/2026\/07\/Wendela-4-672x1030.jpg 672w, https:\/\/www.ingridslaa.nl\/wp-content\/uploads\/2026\/07\/Wendela-4-196x300.jpg 196w, https:\/\/www.ingridslaa.nl\/wp-content\/uploads\/2026\/07\/Wendela-4-460x705.jpg 460w, https:\/\/www.ingridslaa.nl\/wp-content\/uploads\/2026\/07\/Wendela-4.jpg 725w\" data-sizes=\"(max-width: 672px) 100vw, 672px\" data-rel='gallery-1' data-prev-img='https:\/\/www.ingridslaa.nl\/wp-content\/uploads\/2026\/07\/Wendela-4-495x400.jpg' class='lightbox ' data-onclick='3' title='Wendela 4'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-22641 avia-img-lazy-loading-not-22641\"   src=\"https:\/\/www.ingridslaa.nl\/wp-content\/uploads\/2026\/07\/Wendela-4.jpg\" width=\"725\" height=\"1111\"  title='Wendela 4' alt='' srcset=\"https:\/\/www.ingridslaa.nl\/wp-content\/uploads\/2026\/07\/Wendela-4.jpg 725w, https:\/\/www.ingridslaa.nl\/wp-content\/uploads\/2026\/07\/Wendela-4-196x300.jpg 196w, https:\/\/www.ingridslaa.nl\/wp-content\/uploads\/2026\/07\/Wendela-4-672x1030.jpg 672w, https:\/\/www.ingridslaa.nl\/wp-content\/uploads\/2026\/07\/Wendela-4-460x705.jpg 460w\" sizes=\"(max-width: 725px) 100vw, 725px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-22641 avia-img-lazy-loading-22641\"  width=\"495\" height=\"400\" src=\"https:\/\/www.ingridslaa.nl\/wp-content\/uploads\/2026\/07\/Wendela-4-495x400.jpg\" title='Wendela 4' alt='' \/><\/div><\/a><a href=\"https:\/\/www.ingridslaa.nl\/wp-content\/uploads\/2026\/07\/Wendela-5.jpg\" data-srcset=\"https:\/\/www.ingridslaa.nl\/wp-content\/uploads\/2026\/07\/Wendela-5.jpg 1025w, https:\/\/www.ingridslaa.nl\/wp-content\/uploads\/2026\/07\/Wendela-5-300x226.jpg 300w, https:\/\/www.ingridslaa.nl\/wp-content\/uploads\/2026\/07\/Wendela-5-768x579.jpg 768w, https:\/\/www.ingridslaa.nl\/wp-content\/uploads\/2026\/07\/Wendela-5-705x532.jpg 705w\" data-sizes=\"(max-width: 1025px) 100vw, 1025px\" data-rel='gallery-1' data-prev-img='https:\/\/www.ingridslaa.nl\/wp-content\/uploads\/2026\/07\/Wendela-5-495x400.jpg' class='lightbox ' data-onclick='4' title='Wendela 5'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-22642 avia-img-lazy-loading-not-22642\"   src=\"https:\/\/www.ingridslaa.nl\/wp-content\/uploads\/2026\/07\/Wendela-5.jpg\" width=\"1025\" height=\"773\"  title='Wendela 5' alt='' srcset=\"https:\/\/www.ingridslaa.nl\/wp-content\/uploads\/2026\/07\/Wendela-5.jpg 1025w, https:\/\/www.ingridslaa.nl\/wp-content\/uploads\/2026\/07\/Wendela-5-300x226.jpg 300w, https:\/\/www.ingridslaa.nl\/wp-content\/uploads\/2026\/07\/Wendela-5-768x579.jpg 768w, https:\/\/www.ingridslaa.nl\/wp-content\/uploads\/2026\/07\/Wendela-5-705x532.jpg 705w\" sizes=\"(max-width: 1025px) 100vw, 1025px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-22642 avia-img-lazy-loading-22642\"  width=\"495\" height=\"400\" src=\"https:\/\/www.ingridslaa.nl\/wp-content\/uploads\/2026\/07\/Wendela-5-495x400.jpg\" title='Wendela 5' alt='' srcset=\"https:\/\/www.ingridslaa.nl\/wp-content\/uploads\/2026\/07\/Wendela-5-495x400.jpg 495w, https:\/\/www.ingridslaa.nl\/wp-content\/uploads\/2026\/07\/Wendela-5-845x684.jpg 845w\" sizes=\"auto, (max-width: 495px) 100vw, 495px\" \/><\/div><\/a><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>On December 12 and 13, Wendela van Lynden will be exhibiting three-dimensional objects at the gallery.<\/p>\n","protected":false},"author":3,"featured_media":22642,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[98],"tags":[],"class_list":["post-22637","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-guestartist-en"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>December 12 and 13: Wendela van Lynden - Ingrid Slaa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ingridslaa.nl\/en\/december-12-and-13-wendela-van-lynden\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"December 12 and 13: Wendela van Lynden - Ingrid Slaa\" \/>\n<meta property=\"og:description\" content=\"On December 12 and 13, Wendela van Lynden will be exhibiting three-dimensional objects at the gallery.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ingridslaa.nl\/en\/december-12-and-13-wendela-van-lynden\/\" \/>\n<meta property=\"og:site_name\" content=\"Ingrid Slaa\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-15T12:53:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T12:58:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ingridslaa.nl\/wp-content\/uploads\/2026\/07\/Wendela-5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1025\" \/>\n\t<meta property=\"og:image:height\" content=\"773\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"I Slaa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ingridslaa.nl\\\/en\\\/december-12-and-13-wendela-van-lynden\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ingridslaa.nl\\\/en\\\/december-12-and-13-wendela-van-lynden\\\/\"},\"author\":{\"name\":\"I Slaa\",\"@id\":\"https:\\\/\\\/www.ingridslaa.nl\\\/en\\\/#\\\/schema\\\/person\\\/3659b67200290459d0171e1aa3f5fb63\"},\"headline\":\"December 12 and 13: Wendela van Lynden\",\"datePublished\":\"2026-07-15T12:53:13+00:00\",\"dateModified\":\"2026-07-15T12:58:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ingridslaa.nl\\\/en\\\/december-12-and-13-wendela-van-lynden\\\/\"},\"wordCount\":614,\"image\":{\"@id\":\"https:\\\/\\\/www.ingridslaa.nl\\\/en\\\/december-12-and-13-wendela-van-lynden\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ingridslaa.nl\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Wendela-5.jpg\",\"articleSection\":[\"guestartist\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ingridslaa.nl\\\/en\\\/december-12-and-13-wendela-van-lynden\\\/\",\"url\":\"https:\\\/\\\/www.ingridslaa.nl\\\/en\\\/december-12-and-13-wendela-van-lynden\\\/\",\"name\":\"December 12 and 13: Wendela van Lynden - Ingrid Slaa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ingridslaa.nl\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ingridslaa.nl\\\/en\\\/december-12-and-13-wendela-van-lynden\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ingridslaa.nl\\\/en\\\/december-12-and-13-wendela-van-lynden\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ingridslaa.nl\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Wendela-5.jpg\",\"datePublished\":\"2026-07-15T12:53:13+00:00\",\"dateModified\":\"2026-07-15T12:58:11+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.ingridslaa.nl\\\/en\\\/#\\\/schema\\\/person\\\/3659b67200290459d0171e1aa3f5fb63\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ingridslaa.nl\\\/en\\\/december-12-and-13-wendela-van-lynden\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ingridslaa.nl\\\/en\\\/december-12-and-13-wendela-van-lynden\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.ingridslaa.nl\\\/en\\\/december-12-and-13-wendela-van-lynden\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ingridslaa.nl\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Wendela-5.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ingridslaa.nl\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Wendela-5.jpg\",\"width\":1025,\"height\":773},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ingridslaa.nl\\\/en\\\/december-12-and-13-wendela-van-lynden\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ingridslaa.nl\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"December 12 and 13: Wendela van Lynden\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ingridslaa.nl\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.ingridslaa.nl\\\/en\\\/\",\"name\":\"Ingrid Slaa\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ingridslaa.nl\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ingridslaa.nl\\\/en\\\/#\\\/schema\\\/person\\\/3659b67200290459d0171e1aa3f5fb63\",\"name\":\"I Slaa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0aba7f5926f83ff32d8a0d9922ad8e1c5d10d06c3fccea95ab0fc464d6ee14dc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0aba7f5926f83ff32d8a0d9922ad8e1c5d10d06c3fccea95ab0fc464d6ee14dc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0aba7f5926f83ff32d8a0d9922ad8e1c5d10d06c3fccea95ab0fc464d6ee14dc?s=96&d=mm&r=g\",\"caption\":\"I Slaa\"},\"url\":\"https:\\\/\\\/www.ingridslaa.nl\\\/en\\\/author\\\/slaaingmar_36\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"December 12 and 13: Wendela van Lynden - Ingrid Slaa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ingridslaa.nl\/en\/december-12-and-13-wendela-van-lynden\/","og_locale":"en_US","og_type":"article","og_title":"December 12 and 13: Wendela van Lynden - Ingrid Slaa","og_description":"On December 12 and 13, Wendela van Lynden will be exhibiting three-dimensional objects at the gallery.","og_url":"https:\/\/www.ingridslaa.nl\/en\/december-12-and-13-wendela-van-lynden\/","og_site_name":"Ingrid Slaa","article_published_time":"2026-07-15T12:53:13+00:00","article_modified_time":"2026-07-15T12:58:11+00:00","og_image":[{"width":1025,"height":773,"url":"https:\/\/www.ingridslaa.nl\/wp-content\/uploads\/2026\/07\/Wendela-5.jpg","type":"image\/jpeg"}],"author":"I Slaa","twitter_card":"summary_large_image","twitter_misc":{"Written by":false,"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ingridslaa.nl\/en\/december-12-and-13-wendela-van-lynden\/#article","isPartOf":{"@id":"https:\/\/www.ingridslaa.nl\/en\/december-12-and-13-wendela-van-lynden\/"},"author":{"name":"I Slaa","@id":"https:\/\/www.ingridslaa.nl\/en\/#\/schema\/person\/3659b67200290459d0171e1aa3f5fb63"},"headline":"December 12 and 13: Wendela van Lynden","datePublished":"2026-07-15T12:53:13+00:00","dateModified":"2026-07-15T12:58:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ingridslaa.nl\/en\/december-12-and-13-wendela-van-lynden\/"},"wordCount":614,"image":{"@id":"https:\/\/www.ingridslaa.nl\/en\/december-12-and-13-wendela-van-lynden\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ingridslaa.nl\/wp-content\/uploads\/2026\/07\/Wendela-5.jpg","articleSection":["guestartist"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.ingridslaa.nl\/en\/december-12-and-13-wendela-van-lynden\/","url":"https:\/\/www.ingridslaa.nl\/en\/december-12-and-13-wendela-van-lynden\/","name":"December 12 and 13: Wendela van Lynden - Ingrid Slaa","isPartOf":{"@id":"https:\/\/www.ingridslaa.nl\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ingridslaa.nl\/en\/december-12-and-13-wendela-van-lynden\/#primaryimage"},"image":{"@id":"https:\/\/www.ingridslaa.nl\/en\/december-12-and-13-wendela-van-lynden\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ingridslaa.nl\/wp-content\/uploads\/2026\/07\/Wendela-5.jpg","datePublished":"2026-07-15T12:53:13+00:00","dateModified":"2026-07-15T12:58:11+00:00","author":{"@id":"https:\/\/www.ingridslaa.nl\/en\/#\/schema\/person\/3659b67200290459d0171e1aa3f5fb63"},"breadcrumb":{"@id":"https:\/\/www.ingridslaa.nl\/en\/december-12-and-13-wendela-van-lynden\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ingridslaa.nl\/en\/december-12-and-13-wendela-van-lynden\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.ingridslaa.nl\/en\/december-12-and-13-wendela-van-lynden\/#primaryimage","url":"https:\/\/www.ingridslaa.nl\/wp-content\/uploads\/2026\/07\/Wendela-5.jpg","contentUrl":"https:\/\/www.ingridslaa.nl\/wp-content\/uploads\/2026\/07\/Wendela-5.jpg","width":1025,"height":773},{"@type":"BreadcrumbList","@id":"https:\/\/www.ingridslaa.nl\/en\/december-12-and-13-wendela-van-lynden\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ingridslaa.nl\/en\/home\/"},{"@type":"ListItem","position":2,"name":"December 12 and 13: Wendela van Lynden"}]},{"@type":"WebSite","@id":"https:\/\/www.ingridslaa.nl\/en\/#website","url":"https:\/\/www.ingridslaa.nl\/en\/","name":"Ingrid Slaa","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ingridslaa.nl\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.ingridslaa.nl\/en\/#\/schema\/person\/3659b67200290459d0171e1aa3f5fb63","name":"I Slaa","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/0aba7f5926f83ff32d8a0d9922ad8e1c5d10d06c3fccea95ab0fc464d6ee14dc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0aba7f5926f83ff32d8a0d9922ad8e1c5d10d06c3fccea95ab0fc464d6ee14dc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0aba7f5926f83ff32d8a0d9922ad8e1c5d10d06c3fccea95ab0fc464d6ee14dc?s=96&d=mm&r=g","caption":"I Slaa"},"url":"https:\/\/www.ingridslaa.nl\/en\/author\/slaaingmar_36\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ingridslaa.nl\/en\/wp-json\/wp\/v2\/posts\/22637","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ingridslaa.nl\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ingridslaa.nl\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ingridslaa.nl\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ingridslaa.nl\/en\/wp-json\/wp\/v2\/comments?post=22637"}],"version-history":[{"count":13,"href":"https:\/\/www.ingridslaa.nl\/en\/wp-json\/wp\/v2\/posts\/22637\/revisions"}],"predecessor-version":[{"id":22675,"href":"https:\/\/www.ingridslaa.nl\/en\/wp-json\/wp\/v2\/posts\/22637\/revisions\/22675"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ingridslaa.nl\/en\/wp-json\/wp\/v2\/media\/22642"}],"wp:attachment":[{"href":"https:\/\/www.ingridslaa.nl\/en\/wp-json\/wp\/v2\/media?parent=22637"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ingridslaa.nl\/en\/wp-json\/wp\/v2\/categories?post=22637"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ingridslaa.nl\/en\/wp-json\/wp\/v2\/tags?post=22637"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}